{"id":632,"date":"2017-04-14T13:49:14","date_gmt":"2017-04-14T13:49:14","guid":{"rendered":"http:\/\/dorfkind-bbq.de\/dorfkind\/?p=632"},"modified":"2017-04-14T13:49:14","modified_gmt":"2017-04-14T13:49:14","slug":"marinierter-asiastyle-lachs","status":"publish","type":"post","link":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/2017\/04\/14\/marinierter-asiastyle-lachs\/","title":{"rendered":"Marinierter Asiastyle-Lachs"},"content":{"rendered":"<p>Ein sehr beliebtes Fischgericht vom Grill ist Lachs auf Zedernholz gegart. Es gibt hier sehr viele verschiedene Varianten, die irgendwie alle sehr lecker sind. Heute stelle ich meine &#8222;Asiastyle&#8220; Variante vor. So richtig Asiastyle ist hier allerdings nur der Lachs, die Beilagen eher weniger.<\/p>\n<p><strong>Zutaten:<\/strong><\/p>\n<ul>\n<li>Lachs (Menge nach Bedarf, die Marinade ist f\u00fcr ca. 650g)<\/li>\n<li>3EL Sojasauce<\/li>\n<li>2EL Oliven\u00f6l (<a href=\"https:\/\/www.ankerkraut.de\/oel-saucen\/band-of-chefs-olivenoel-750ml\">Band of Chefs<\/a>)<\/li>\n<li>1 Zitrone (Saft)<\/li>\n<li>1TL Zucker<\/li>\n<li>1,5 TL frischer Ingwer fein gehackt<\/li>\n<li>1 Knoblauchzehe fein gehackt<\/li>\n<li>1 TL 9-Pfeffer Symphonie (<a href=\"https:\/\/www.ankerkraut.de\/\">Ankerkraut<\/a>)<\/li>\n<li>1\/2 TL Chili Flocken\u00a0(<a href=\"https:\/\/www.ankerkraut.de\/\">Ankerkraut<\/a>)<\/li>\n<li>Zedernholzplanke<\/li>\n<\/ul>\n<p><strong>Zubereitung:<\/strong><\/p>\n<p>Als erstes muss die Planke f\u00fcr 3 Stunden gew\u00e4ssert werden. Am einfachsten ist es die Planke im Sp\u00fclbecken baden zu lassen. 1-2 Tassen mit Wasser gef\u00fcllt halten die Planke unterwasser.<\/p>\n<p><a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-635\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>Nun vermengen wir alle Zutaten f\u00fcr die Marinade in einer Sch\u00fcssel. Um den Lachs zu marinieren legt\u00a0man diesen am einfachsten in einen Gefrierbeutel und gibt die Marinade dazu. Die T\u00fcte verschlie\u00dfen und f\u00fcr 45 Minuten in den K\u00fchlschrank legen.<\/p>\n<p><a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-636\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a> <a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-3-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-637\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>Nun ist es an der Zeit den Grill vorzubereiten. F\u00fcr Lachs wird der Grill bei 180-200 Grad eingeregelt. Der Lachs kommt erst auf die Planke, wenn diese anf\u00e4ngt zu knacken\/knistern. Die Garzeit betr\u00e4gt ca. 15 Minuten (Kerntemperatur 57 Grad).<br \/>\nAls Beilage gab es Pilze (In Butter mit Ankerkraut Kr\u00e4uterbutter-Gew\u00fcrz), Bratkartoffeln (Salz, Pfeffer und Ankerkraut ger\u00e4ucherter Paprika) und Gurkensalat.<\/p>\n<p><a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-638\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a> <a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-5-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-639\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-5-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a> <a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-6-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-640\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/04\/lachsmariniert-14.-April-2017-6-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>Guten Appetit!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein sehr beliebtes Fischgericht vom Grill ist Lachs auf Zedernholz gegart. Es gibt hier sehr viele verschiedene Varianten, die irgendwie alle sehr lecker sind. Heute stelle ich meine &#8222;Asiastyle&#8220; Variante vor. So richtig Asiastyle ist hier allerdings nur der Lachs, die Beilagen eher weniger. Zutaten:&nbsp;<a class=\"read-more\" href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/2017\/04\/14\/marinierter-asiastyle-lachs\/\">&hellip;<\/a><\/p>\n","protected":false},"author":1,"featured_media":639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10,14,3],"tags":[28,31,43,59,71,81],"class_list":["post-632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-rezepte","category-bbq","category-fisch","category-rezepte","tag-asiatisch","tag-bbq","tag-fisch","tag-holzplanke","tag-lachs","tag-planke"],"_links":{"self":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/posts\/632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/comments?post=632"}],"version-history":[{"count":0,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/posts\/632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/media\/639"}],"wp:attachment":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/media?parent=632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/categories?post=632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/tags?post=632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}