{"id":966,"date":"2017-11-28T19:37:17","date_gmt":"2017-11-28T19:37:17","guid":{"rendered":"http:\/\/dorfkind-bbq.de\/dorfkind\/?p=966"},"modified":"2017-11-28T19:37:17","modified_gmt":"2017-11-28T19:37:17","slug":"schweinefilet-aus-dem-wok","status":"publish","type":"post","link":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/2017\/11\/28\/schweinefilet-aus-dem-wok\/","title":{"rendered":"Schweinefilet aus dem Wok"},"content":{"rendered":"<p>Rezepte f\u00fcr die Zubereitung von Schweinefilet gibt es wie Sand am Meer, das St\u00fcck Fleisch erm\u00f6glicht auch sehr viele verschiedene Arten es zu verwenden. Wenn man aber ein Rezept f\u00fcr den Wok sucht, dann wir die Auswahl doch schon etwas d\u00fcnn. Zusammen mit Bohnen, Fr\u00fchlingszwiebel, Paprika, Zucchini und einer leckeren W\u00fcrzsauce habe ich hier ein Wok Rezepte f\u00fcr euch. Als Beilage empfehle ich Reis.<\/p>\n<p><strong>Zutaten:<\/strong><\/p>\n<ul>\n<li>600g Schweinefilet<\/li>\n<li>250g gr\u00fcne Bohnen<\/li>\n<li>4 Fr\u00fchlingszwiebel<\/li>\n<li>1 roter Paprika<\/li>\n<li>1 kleine (mini) Zucchini<\/li>\n<li>1-2 Knobauchzehen<\/li>\n<li>ca. 2cm frischen Ingwer<\/li>\n<li>\u00d6l<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">Marinade f\u00fcr das Fleisch<\/p>\n<ul>\n<li>4EL Sojasauce<\/li>\n<li>1EL Reisessig<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">W\u00fcrzsauce<\/p>\n<ul>\n<li>2EL Sojasauce<\/li>\n<li>150ml Wasser<\/li>\n<li>1EL Hoisin Sauce<\/li>\n<li>1\/2 EL Austernsauce<\/li>\n<li>1\/2 EL Fischsauce<\/li>\n<li>1\/2EL Reisessig<\/li>\n<li>1TL Gem\u00fcsebr\u00fche (pulver)<\/li>\n<li>1TL (geh\u00e4uft) St\u00e4rke<\/li>\n<\/ul>\n<p><strong>Zubereitung:<\/strong><\/p>\n<p>Zuerst wird das Schweinefilet in ca. 1cm dicke Scheiben geschnitten, die Scheiben werden dann noch in Streifen geschnitten (3 Streifen je Scheibe). Die Filetstreifen werden f\u00fcr 3-4 Stunden in 4EL Sojasauce und 1EL Reisessig mariniert.<\/p>\n<p>Die Bohnen werden 10 Minuten gekocht und dann mit kaltem Wasser abgeschreckt. Die Fr\u00fchlingszwiebel in Ringe schneiden, den Paprika und die Zucchini werden in Streifen geschnitten. Die Gr\u00f6\u00dfe des geschnittenen Gem\u00fcse wird so gew\u00e4hlt, dass es zu den Filetstreifen passt.<br \/>\nKnoblauch und Ingwer werden klein gew\u00fcrfelt und mit 2EL \u00d6l vermischt, diese Mischung wird sp\u00e4ter ben\u00f6tigt um das Gem\u00fcse zu wokken. Das Verh\u00e4ltnis Knoblauch zu Inwger sollte 1:1 sein.<\/p>\n<p>Die Zutaten der W\u00fcrzsauce werden in einen Mixbecher gegeben und einmal kr\u00e4ftig durchgesch\u00fcttelt. Noch ein kleine Hinweis, die Austernsauce hat einen sehr dominanten Geschmack und \u00fcberdeckt leicht alles andere. Man kann die Austernsauce entweder komplett weglassen oder weniger verwenden. Ich empfehle hier einfach etwas mit den Mengen zu spielen um ein f\u00fcr sich selbst perfektes Mischverh\u00e4ltnis zu bekommen.<\/p>\n<p>Nun geht es ans wokken, wir beginnen mit dem Schweinefilet. Das Fleisch wird Portionsweise (2-3 Portionen) mit je einem EL \u00d6l f\u00fcr 1-2 Minuten gewokked. Die Gr\u00f6\u00dfe der Portion und die Dauer h\u00e4ngt hier von den eigenen F\u00e4higkeiten, der Gr\u00f6\u00dfe des Woks und der Leistung des Wokbrenners ab. Das Fleisch wird nun zur Seite gestellt und es geht mit dem Gem\u00fcse weiter.<br \/>\nAls erstes wird die Mischung aus Knoblauch, Ingwer und \u00d6l in de Wok gegeben. Sobald es duftet wird nach und nach das Gem\u00fcse in der Reihenfolge Zucchini, Paprika, Bohnen und Fr\u00fchlingszwiebel in den Wok gegeben und f\u00fcr 2-3 Minuten gewokked. Jetzt kommt das Fleisch und die W\u00fcrzsauce mit in den Wok und alles wird ordentlich vermengt. Die W\u00fcrzsauce muss vor der Verwendung nochmals kr\u00e4ftig gesch\u00fcttelt werden, da sich hier mit der Zeit die St\u00e4rke absetzt.<\/p>\n<p>Ich w\u00fcnsche einen guten Appetit und viel Spa\u00df beim &#8222;Nach-Wokken&#8220;.<\/p>\n<p><a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/11\/wok_schweinefile-28.-November-2017-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-973\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/11\/wok_schweinefile-28.-November-2017-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a> <a href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/11\/wok_schweinefile-31.-Oktober-2017-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-974\" src=\"http:\/\/dorfkind-bbq.de\/dorfkind\/wp-content\/uploads\/2017\/11\/wok_schweinefile-31.-Oktober-2017-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rezepte f\u00fcr die Zubereitung von Schweinefilet gibt es wie Sand am Meer, das St\u00fcck Fleisch erm\u00f6glicht auch sehr viele verschiedene Arten es zu verwenden. Wenn man aber ein Rezept f\u00fcr den Wok sucht, dann wir die Auswahl doch schon etwas d\u00fcnn. Zusammen mit Bohnen, Fr\u00fchlingszwiebel,&nbsp;<a class=\"read-more\" href=\"https:\/\/www.dorfkind-bbq.de\/dorfkind\/2017\/11\/28\/schweinefilet-aus-dem-wok\/\">&hellip;<\/a><\/p>\n","protected":false},"author":1,"featured_media":974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,15,3,24,5,6],"tags":[28,45,50,89,97],"class_list":["post-966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-rezepte","category-fleisch","category-rezepte","category-schwein","category-uncategorized","category-wok","tag-asiatisch","tag-fleisch","tag-gemuese","tag-schwein","tag-wok"],"_links":{"self":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/posts\/966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/comments?post=966"}],"version-history":[{"count":0,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/posts\/966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/media\/974"}],"wp:attachment":[{"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/media?parent=966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/categories?post=966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dorfkind-bbq.de\/dorfkind\/wp-json\/wp\/v2\/tags?post=966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}